{"id":155,"count":2,"description":"A <strong>Mel i Llimona<\/strong>, creiem en el talent local i en un equip que comparteixi la nostra passi\u00f3 per la gastronomia i el sabor aut\u00e8ntic. La nostra secci\u00f3 \"<strong>Treballa amb nosaltres<\/strong>\" \u00e9s el punt de trobada per a professionals que volen unir-se a un projecte en creixement, on el bon ambient i les oportunitats de desenvolupament s\u00f3n clau.\r\n\r\nSi ets un <strong>cambrer\/a, barista, artes\u00e0 o administratiu<\/strong> amb ganes de superar-te i aportar la teva creativitat, aqu\u00ed trobar\u00e0s el teu lloc. Busquem persones proactives, amb experi\u00e8ncia en el sector de l'hostaleria i l'artesania, i sobretot, amb un gran amor per la cuina mediterr\u00e0nia i els productes de qualitat.\r\n\r\nEl nostre objectiu \u00e9s construir un equip s\u00f2lid i comprom\u00e8s que esdevingui el cor de Mel i Llimona. Descobreix les oportunitats i <strong>uneix-te a la nostra fam\u00edlia!<\/strong>","link":"https:\/\/melillimonartesania.com\/ca\/category\/treballa-amb-nosaltres\/","name":"Treballa amb nosaltres","slug":"treballa-amb-nosaltres","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Treballa amb nosaltres archivos - Mel i Llimona &amp; iCanyella: Artesan\u00eda, Gastronom\u00eda y Comunidad en Badalona<\/title>\n<meta name=\"description\" content=\"Uneix-te a Mel i Llimona. Oportunitats de feina a Badalona per a cambrers, baristes, cuiners i m\u00e9s. Sigues part d&#039;un equip apassionat per la cuina.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/melillimonartesania.com\/ca\/category\/treballa-amb-nosaltres\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Treballa amb nosaltres archivos\" \/>\n<meta property=\"og:description\" content=\"Uneix-te a Mel i Llimona. Oportunitats de feina a Badalona per a cambrers, baristes, cuiners i m\u00e9s. Sigues part d&#039;un equip apassionat per la cuina.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/melillimonartesania.com\/ca\/category\/treballa-amb-nosaltres\/\" \/>\n<meta property=\"og:site_name\" content=\"Mel i Llimona &amp; iCanyella: Artesan\u00eda, Gastronom\u00eda y Comunidad en Badalona\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/melillimonartesania.com\\\/ca\\\/category\\\/treballa-amb-nosaltres\\\/\",\"url\":\"https:\\\/\\\/melillimonartesania.com\\\/ca\\\/category\\\/treballa-amb-nosaltres\\\/\",\"name\":\"Treballa amb nosaltres archivos - Mel i Llimona &amp; iCanyella: Artesan\u00eda, Gastronom\u00eda y Comunidad en Badalona\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/melillimonartesania.com\\\/ca\\\/#website\"},\"description\":\"Uneix-te a Mel i Llimona. Oportunitats de feina a Badalona per a cambrers, baristes, cuiners i m\u00e9s. Sigues part d'un equip apassionat per la cuina.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/melillimonartesania.com\\\/ca\\\/category\\\/treballa-amb-nosaltres\\\/#breadcrumb\"},\"inLanguage\":\"ca\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/melillimonartesania.com\\\/ca\\\/category\\\/treballa-amb-nosaltres\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/melillimonartesania.com\\\/ca\\\/mel-i-llimona-icanyella\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Treballa amb nosaltres\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/melillimonartesania.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/melillimonartesania.com\\\/ca\\\/\",\"name\":\"Mel i Llimona &amp; iCanyella: Artesan\u00eda, Gastronom\u00eda y Comunidad en Badalona\",\"description\":\"Mel i Llimona &amp; iCanyella, un espacio que conserva su esencia artesanal  y a\u00f1ade degustaci\u00f3n ecol\u00f3gica, mercado sostenible y un espacio para la comunidad en Badalona.\",\"publisher\":{\"@id\":\"https:\\\/\\\/melillimonartesania.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/melillimonartesania.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":[\"Organization\",\"Place\",\"LocalBusiness\"],\"@id\":\"https:\\\/\\\/melillimonartesania.com\\\/ca\\\/#organization\",\"name\":\"Mel i Llimona Creaci\u00f3 Artesanal S.C.C.L.\",\"alternateName\":\"Mel i Llimona iCanyella\",\"url\":\"https:\\\/\\\/melillimonartesania.com\\\/ca\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/melillimonartesania.com\\\/ca\\\/category\\\/treballa-amb-nosaltres\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/melillimonartesania.com\\\/ca\\\/category\\\/treballa-amb-nosaltres\\\/#local-main-organization-logo\"},\"description\":\"Mel i Llimona Artesan\u00eda en Badalona: Desde 2018, somos el taller de referencia para la restauraci\u00f3n profesional de muebles antiguos y el arte del 'hazlo t\u00fa mismo'. Hemos evolucionado a iCanyella en Badalona, un espacio que integra nuestro taller tradicional con un mercado local de artesan\u00eda sostenible y degustaci\u00f3n de productos ecol\u00f3gicos. Vis\u00edtanos para tus proyectos de restauraci\u00f3n, talleres comunitarios y para apoyar el comercio justo en la zona.\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"},\"address\":{\"@id\":\"https:\\\/\\\/melillimonartesania.com\\\/ca\\\/category\\\/treballa-amb-nosaltres\\\/#local-main-place-address\"},\"telephone\":[\"+34 635 422 982\"],\"contactPoint\":{\"@type\":\"ContactPoint\",\"telephone\":\"+34 635 422 982\",\"email\":\"info@melillimonartesania.com\"},\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\"],\"opens\":\"17:00\",\"closes\":\"20:00\"},{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\"],\"opens\":\"09:00\",\"closes\":\"20:00\"},{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Saturday\"],\"opens\":\"09:00\",\"closes\":\"14:00\"},{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Sunday\"],\"opens\":\"00:00\",\"closes\":\"00:00\"}],\"email\":\"hola@melillimonartesania.com\",\"areaServed\":\"Badalona, Barcelona, Maresme\",\"vatID\":\"F56933963\",\"taxID\":\"F56933963\",\"currenciesAccepted\":\"EUR\",\"paymentAccepted\":\"Contado, tarjeta\"},{\"@type\":\"PostalAddress\",\"@id\":\"https:\\\/\\\/melillimonartesania.com\\\/ca\\\/category\\\/treballa-amb-nosaltres\\\/#local-main-place-address\",\"streetAddress\":\"Carrer d'Arn\u00fas, 36\",\"addressLocality\":\"Badalona\",\"postalCode\":\"08911\",\"addressRegion\":\"Catalunya\",\"addressCountry\":\"ES\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/melillimonartesania.com\\\/ca\\\/category\\\/treballa-amb-nosaltres\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/melillimonartesania.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/melillimona-icanyella-black.svg\",\"contentUrl\":\"https:\\\/\\\/melillimonartesania.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/melillimona-icanyella-black.svg\",\"width\":135,\"height\":20,\"caption\":\"Mel i Llimona Creaci\u00f3 Artesanal S.C.C.L.\"}]}<\/script>\n<meta name=\"geo.placename\" content=\"Badalona\" \/>\n<meta name=\"geo.region\" content=\"Espanya\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Treballa amb nosaltres archivos - Mel i Llimona &amp; iCanyella: Artesan\u00eda, Gastronom\u00eda y Comunidad en Badalona","description":"Uneix-te a Mel i Llimona. Oportunitats de feina a Badalona per a cambrers, baristes, cuiners i m\u00e9s. Sigues part d'un equip apassionat per la cuina.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/melillimonartesania.com\/ca\/category\/treballa-amb-nosaltres\/","og_locale":"ca_ES","og_type":"article","og_title":"Treballa amb nosaltres archivos","og_description":"Uneix-te a Mel i Llimona. Oportunitats de feina a Badalona per a cambrers, baristes, cuiners i m\u00e9s. Sigues part d'un equip apassionat per la cuina.","og_url":"https:\/\/melillimonartesania.com\/ca\/category\/treballa-amb-nosaltres\/","og_site_name":"Mel i Llimona &amp; iCanyella: Artesan\u00eda, Gastronom\u00eda y Comunidad en Badalona","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/melillimonartesania.com\/ca\/category\/treballa-amb-nosaltres\/","url":"https:\/\/melillimonartesania.com\/ca\/category\/treballa-amb-nosaltres\/","name":"Treballa amb nosaltres archivos - Mel i Llimona &amp; iCanyella: Artesan\u00eda, Gastronom\u00eda y Comunidad en Badalona","isPartOf":{"@id":"https:\/\/melillimonartesania.com\/ca\/#website"},"description":"Uneix-te a Mel i Llimona. Oportunitats de feina a Badalona per a cambrers, baristes, cuiners i m\u00e9s. Sigues part d'un equip apassionat per la cuina.","breadcrumb":{"@id":"https:\/\/melillimonartesania.com\/ca\/category\/treballa-amb-nosaltres\/#breadcrumb"},"inLanguage":"ca"},{"@type":"BreadcrumbList","@id":"https:\/\/melillimonartesania.com\/ca\/category\/treballa-amb-nosaltres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/melillimonartesania.com\/ca\/mel-i-llimona-icanyella\/"},{"@type":"ListItem","position":2,"name":"Treballa amb nosaltres"}]},{"@type":"WebSite","@id":"https:\/\/melillimonartesania.com\/ca\/#website","url":"https:\/\/melillimonartesania.com\/ca\/","name":"Mel i Llimona &amp; iCanyella: Artesan\u00eda, Gastronom\u00eda y Comunidad en Badalona","description":"Mel i Llimona &amp; iCanyella, un espacio que conserva su esencia artesanal  y a\u00f1ade degustaci\u00f3n ecol\u00f3gica, mercado sostenible y un espacio para la comunidad en Badalona.","publisher":{"@id":"https:\/\/melillimonartesania.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/melillimonartesania.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":["Organization","Place","LocalBusiness"],"@id":"https:\/\/melillimonartesania.com\/ca\/#organization","name":"Mel i Llimona Creaci\u00f3 Artesanal S.C.C.L.","alternateName":"Mel i Llimona iCanyella","url":"https:\/\/melillimonartesania.com\/ca\/","logo":{"@id":"https:\/\/melillimonartesania.com\/ca\/category\/treballa-amb-nosaltres\/#local-main-organization-logo"},"image":{"@id":"https:\/\/melillimonartesania.com\/ca\/category\/treballa-amb-nosaltres\/#local-main-organization-logo"},"description":"Mel i Llimona Artesan\u00eda en Badalona: Desde 2018, somos el taller de referencia para la restauraci\u00f3n profesional de muebles antiguos y el arte del 'hazlo t\u00fa mismo'. Hemos evolucionado a iCanyella en Badalona, un espacio que integra nuestro taller tradicional con un mercado local de artesan\u00eda sostenible y degustaci\u00f3n de productos ecol\u00f3gicos. Vis\u00edtanos para tus proyectos de restauraci\u00f3n, talleres comunitarios y para apoyar el comercio justo en la zona.","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"},"address":{"@id":"https:\/\/melillimonartesania.com\/ca\/category\/treballa-amb-nosaltres\/#local-main-place-address"},"telephone":["+34 635 422 982"],"contactPoint":{"@type":"ContactPoint","telephone":"+34 635 422 982","email":"info@melillimonartesania.com"},"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday"],"opens":"17:00","closes":"20:00"},{"@type":"OpeningHoursSpecification","dayOfWeek":["Tuesday","Wednesday","Thursday","Friday"],"opens":"09:00","closes":"20:00"},{"@type":"OpeningHoursSpecification","dayOfWeek":["Saturday"],"opens":"09:00","closes":"14:00"},{"@type":"OpeningHoursSpecification","dayOfWeek":["Sunday"],"opens":"00:00","closes":"00:00"}],"email":"hola@melillimonartesania.com","areaServed":"Badalona, Barcelona, Maresme","vatID":"F56933963","taxID":"F56933963","currenciesAccepted":"EUR","paymentAccepted":"Contado, tarjeta"},{"@type":"PostalAddress","@id":"https:\/\/melillimonartesania.com\/ca\/category\/treballa-amb-nosaltres\/#local-main-place-address","streetAddress":"Carrer d'Arn\u00fas, 36","addressLocality":"Badalona","postalCode":"08911","addressRegion":"Catalunya","addressCountry":"ES"},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/melillimonartesania.com\/ca\/category\/treballa-amb-nosaltres\/#local-main-organization-logo","url":"https:\/\/melillimonartesania.com\/wp-content\/uploads\/2025\/09\/melillimona-icanyella-black.svg","contentUrl":"https:\/\/melillimonartesania.com\/wp-content\/uploads\/2025\/09\/melillimona-icanyella-black.svg","width":135,"height":20,"caption":"Mel i Llimona Creaci\u00f3 Artesanal S.C.C.L."}]},"geo.placename":"Badalona","geo.region":"Espanya"},"_links":{"self":[{"href":"https:\/\/melillimonartesania.com\/ca\/wp-json\/wp\/v2\/categories\/155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/melillimonartesania.com\/ca\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/melillimonartesania.com\/ca\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/melillimonartesania.com\/ca\/wp-json\/wp\/v2\/posts?categories=155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}